{"id":47325,"date":"2020-08-05T15:48:43","date_gmt":"2020-08-05T18:48:43","guid":{"rendered":"http:\/\/www.saopaulo.sp.leg.br\/apartes\/?p=47325"},"modified":"2025-11-26T06:29:46","modified_gmt":"2025-11-26T09:29:46","slug":"voz-negra-e-pioneira-nas-tribunas","status":"publish","type":"post","link":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/","title":{"rendered":"Voz negra e pioneira nas tribunas"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tempo estimado de leitura: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">minutos<\/span><\/span><p><strong>Fausto Salvadori |<\/strong> <a href=\"mailto:fausto@saopaulo.sp.leg.br\">fausto@saopaulo.sp.leg.br<\/a><br \/>\n<strong>Rodrigo Garcia |<\/strong> <a href=\"mailto:rodrigogarcia@saopaulo.sp.leg.br\">rodrigogarcia@saopaulo.sp.leg.br<\/a><\/p>\n<p>Com um nome raro, Theod<span style=\"font-size: 1em\">osina Ros\u00e1rio Ribeiro nasceu em 1925, quando as mulheres ainda n\u00e3o tinham nem o direito a voto. Em quase 90 anos de vida, ela superou desafios e foi eleita a primeira vereadora negra da C\u00e2mara Municipal de S\u00e3o Paulo (CMSP). Como con<\/span><span style=\"font-size: 1em\">sequ\u00eancia de seus esfor\u00e7os em educa\u00e7\u00e3o e na pol\u00edtica, ela tamb\u00e9m foi professora, diretora de escola, advogada e deputada estadual. Sempre lutou por mais liberdades para as mulheres e todas as pessoas negras.<\/span><\/p>\n<p>Sua paix\u00e3o pela pol\u00edtica teve uma forte influ\u00eancia do pai, o capit\u00e3o da For\u00e7a P\u00fablica (atual Pol\u00edcia Militar) Jos\u00e9 Ign\u00e1cio do Ros\u00e1rio, que era admirador do presidente Get\u00falio Vargas e do ex-governador de S\u00e3o Paulo Ademar de Barros.<\/p>\n<p>Seu nome tamb\u00e9m \u00e9 influ\u00eancia do pai. \u201cEra pra eu me chamar Teodora, mas papai achou muito pesado para uma crian\u00e7a e escolheu este\u201d, contou numa entrevista \u00e0 <a href=\"http:\/\/www.saopaulo.sp.leg.br\/wp-content\/uploads\/2014\/11\/revista_do_parlamento_paulistano_n2.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Revista do Parlamento Paulistano<\/a> em 2012.<\/p>\n\n\n\n[aesop_video  src=&#8221;youtube&#8221; id=&#8221;b6UCzt2NJh8&#8243; width=&#8221;80%&#8221; align=&#8221;center&#8221; disable_for_mobile=&#8221;off&#8221; loop=&#8221;off&#8221; controls=&#8221;on&#8221; mute=&#8221;off&#8221; autoplay=&#8221;off&#8221; viewstart=&#8221;off&#8221; viewend=&#8221;off&#8221; show_subtitles=&#8221;on&#8221; lang_pref=&#8221;pt&#8221; revealfx=&#8221;inplace&#8221; overlay_revealfx=&#8221;off&#8221;]\n<div class=\"infografico-desktop\">\n<h3 style=\"text-align: center\"><strong><span style=\"color: #8c7ca5\">EDUCA\u00c7\u00c3O POL\u00cdTICA <\/span><\/strong><\/h3>\n<\/div>\n<div class=\"infografico-mobile\">\n<h4 style=\"text-align: center\"><strong><span style=\"color: #8c7ca5\">EDUCA\u00c7\u00c3O POL\u00cdTICA<\/span><\/strong><\/h4>\n<\/div>\n<p>Filha do capit\u00e3o Ros\u00e1rio e da dona de casa Rosa, Theodosina nasceu em Barretos, interior de S\u00e3o Paulo, onde passou parte da inf\u00e2ncia. Depois morou em Araraquara e Pirassununga, at\u00e9 se estabelecer na capital. A jovem estudou Letras em Mogi das Cruzes, na Grande S\u00e3o Paulo. Formada, come\u00e7ou a trabalhar como professora na capital paulista.<\/p>\n<p>Prestou um concurso e se tornou diretora de escola, considerado por ela um cargo pol\u00edtico. \u201cAs diretoras fazem muita pol\u00edtica, no bom sentido da palavra\u201d, recordava-se com orgulho. \u201cNa minha \u00e9poca, elas lutavam muito para que o professorado tivesse melhores condi\u00e7\u00f5es de trabalho\u201d. Ali\u00e1s, a ex-parlamentar defendia que seus colegas professores seguissem a carreira pol\u00edtica, por terem \u201cboa no\u00e7\u00e3o da realidade do Pa\u00eds\u201d.<\/p>\n<div class=\"infografico-desktop\">\n<h3 style=\"text-align: center\"><strong><span style=\"color: #8c7ca5\">LINHA DO TEMPO<\/span><\/strong><\/h3>\n<\/div>\n<div class=\"infografico-mobile\">\n<h4 style=\"text-align: center\"><strong><span style=\"color: #8c7ca5\">LINHA DO TEMPO<\/span><\/strong><\/h4>\n<\/div>\n<div class=\"infografico-desktop\" style=\"text-align: center\" align=\"center\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/cdn.knightlab.com\/libs\/timeline3\/latest\/embed\/index.html?source=1e9L6gP9q1fZo7RmXD3jcq2tf9-plIntn0_iYXif1hyI&#038;font=Default&#038;lang=pt-br&#038;initial_zoom=2&#038;height=650\" width=\"95%\" height=\"750px\" scrolling=\"yes\" class=\"iframe-class\" frameborder=\"0\"><\/iframe>\n<\/div>\n<div class=\"infografico-mobile\" style=\"text-align: center\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/cdn.knightlab.com\/libs\/timeline3\/latest\/embed\/index.html?source=1e9L6gP9q1fZo7RmXD3jcq2tf9-plIntn0_iYXif1hyI&#038;font=Default&#038;lang=pt-br&#038;initial_zoom=2&#038;height=650\" width=\"100%\" height=\"500px\" scrolling=\"yes\" class=\"iframe-class\" frameborder=\"0\"><\/iframe>\n<\/div>\n<h3><\/h3>\n<div class=\"infografico-desktop\">\n<h3 style=\"text-align: center\"><strong><span style=\"color: #8c7ca5\">PARLAMENTOS <\/span><\/strong><\/h3>\n<\/div>\n<div class=\"infografico-mobile\">\n<h4 style=\"text-align: center\"><strong><span style=\"color: #8c7ca5\">PARLAMENTOS<\/span><\/strong><\/h4>\n<\/div>\n<p>Em S\u00e3o Paulo, Theodosina graduou-se tamb\u00e9m em Direito. E, com o incentivo do empres\u00e1rio <a href=\"http:\/\/www.fgv.br\/cpdoc\/acervo\/dicionarios\/verbete-biografico\/camargo-adalberto\" target=\"_blank\" rel=\"noopener noreferrer\">Adalberto Camargo<\/a>, o primeiro deputado federal negro por S\u00e3o Paulo, decidiu entrar na carreira pol\u00edtica. Em 1968, elegeu-se vereadora com 26.846 votos, a segunda mais votada do Movimento Democr\u00e1tico Brasileiro (MDB), partido de oposi\u00e7\u00e3o \u00e0 ditadura militar. Em 1970, conquistou uma cadeira na Assembleia Legislativa, onde ficou at\u00e9 1983.<\/p>\n\n[aesop_quote  type=&#8221;block&#8221; background=&#8221;#282828&#8243; text=&#8221;#ffffff&#8221; align=&#8221;left&#8221; size=&#8221;1&#8243; quote=&#8221;\u201cMulher negra sofre preconceito por ser mulher e por ser negra.\u201d&#8221; cite=&#8221;Theodosina Ros\u00e1rio Ribeiro &#8221; revealfx=&#8221;off&#8221;]\n<p>Da \u00e9poca como parlamentar, lamentava n\u00e3o ter podido fazer muito pela popula\u00e7\u00e3o, j\u00e1 que o Brasil estava em uma ditadura e os vereadores e deputados estaduais tinham pouco poder. Mas se orgulhava de ter participado de muitas comiss\u00f5es, sempre preocupada com as quest\u00f5es sociais. \u201cA mulher negra sofre preconceito por ser mulher e por ser negra, ganha menos do que os homens e menos do que as mulheres brancas\u201d, denunciava.<\/p>\n<p>Ideologicamente, dizia acreditar numa democracia plena, respeitando os valores sociais, principalmente os inseridos na Constitui\u00e7\u00e3o: \u201cSou uma democrata, contra o populismo barato e contra o radicalismo\u201d. Em 1982, concorreu pela quarta vez seguida a uma vaga na Assembleia Legislativa. Por\u00e9m n\u00e3o conseguiu se reeleger. Theodosina levou um choque, ficou triste e \u201cfrustrada por n\u00e3o poder continuar com meus projetos\u201d.<\/p>\n\n<div class=\"infografico-desktop\">\n<h3 style=\"text-align: center\"><strong><span style=\"color: #8c7ca5\">EMPODERAMENTO FEMININO NEGRO<\/span><\/strong><\/h3>\n<\/div>\n<div class=\"infografico-mobile\">\n<h4 style=\"text-align: center\"><strong><span style=\"color: #8c7ca5\">EMPODERAMENTO FEMININO NEGRO<\/span><\/strong><\/h4>\n<\/div>\n<p>Mas a professora e advogada n\u00e3o abandonou a vida p\u00fablica. Fez parte da <a href=\"http:\/\/www.oabsp.org.br\/comissoes2010\/igualdade-racial\">Comiss\u00e3o de Igualdade Racial<\/a> da Ordem dos Advogados do Brasil (OAB) de S\u00e3o Paulo, da qual se tornou membro consultora em\u00e9rita.<\/p>\n\n[aesop_quote  type=&#8221;block&#8221; background=&#8221;#282828&#8243; text=&#8221;#ffffff&#8221; align=&#8221;right&#8221; size=&#8221;1&#8243; quote=&#8221;\u201cO Pa\u00eds tem uma d\u00edvida hist\u00f3rica enorme com os negros, que ap\u00f3s a \u2018aboli\u00e7\u00e3o\u2019 da escravatura foram abandonados.\u201d&#8221; revealfx=&#8221;off&#8221;]\n<p>Theodosina era a favor das cotas raciais para os afrodescendentes entrarem nas universidades. \u201cO negro precisa se preparar para vencer na vida.\u201d Segundo ela, \u201co Pa\u00eds tem uma d\u00edvida hist\u00f3rica enorme com os negros, que ap\u00f3s a \u2018aboli\u00e7\u00e3o\u2019 \u2013 essa aboli\u00e7\u00e3o deve vir entre aspas \u2013\u00a0da escravatura foram abandonados\u201d.<\/p>\n<p>A militante dizia nunca ter sofrido um preconceito direto. \u201cMas a gente percebia que havia racismo\u201d, afirmou em entrevista \u00e0 <strong>Apartes<\/strong> em 2018, uma de suas \u00faltimas. Ela se lembrou que sua irm\u00e3, Maria de Lourdes, foi v\u00edtima de hostilidades em Pirassununga por ter entrado na Escola Normal para fazer o magist\u00e9rio. Mesmo assim, tornou-se a primeira professora negra da cidade.<\/p>\n\n<p>Em rela\u00e7\u00e3o ao racismo no Brasil, considerava \u201cvelado\u201d. \u201cMas \u00e9 muito maior do que nos Estados Unidos, que j\u00e1 elegeram um presidente negro, Barack Obama.\u201d Em palestras que dava para as comunidades negras, Theodosina defendia a import\u00e2ncia da mobiliza\u00e7\u00e3o pol\u00edtica e social, principalmente para mulheres negras jovens. \u201cA mulher tem mais sensibilidade do que o homem; ela deveria participar mais da pol\u00edtica\u201d, aconselhava. \u201cOs negros, e as mulheres negras em especial, t\u00eam de ocupar todos os espa\u00e7os na sociedade.\u201d Otimista, percebia avan\u00e7os. \u201cAs coisas est\u00e3o melhorando: j\u00e1 vemos engenheiras negras, m\u00e9dicas negras, advogadas negras\u201d, alegrava-se.<\/p>\n<div class=\"infografico-desktop\">\n[aesop_gallery  id=&#8221;49360&#8243; revealfx=&#8221;off&#8221; overlay_revealfx=&#8221;off&#8221;]\n<\/div>\n<div class=\"infografico-mobile\">\n[aesop_gallery id=&#8221;49679&#8243;]\n<\/div>\n\n<p>A C\u00e2mara Municipal de S\u00e3o Paulo, em 2004, homenageou Theodosina concedendo-lhe o T\u00edtulo de Cidad\u00e3 Paulistana. A ent\u00e3o vereadora Claudete Alves, ao apresentar a proposta da homenagem, definiu a ex-parlamentar como \u201cuma das mulheres negras que melhor representam o esfor\u00e7o, a abnega\u00e7\u00e3o e o esp\u00edrito insubmisso do povo afro-brasileiro\u201d.<\/p>\n<p>Em 2014, a Assembleia Legislativa de S\u00e3o Paulo (Alesp) criou a medalha Theodosina Ros\u00e1rio Ribeiro, conferida a \u201cmulheres ou entidades de mulheres que se destacarem na sociedade em raz\u00e3o de sua contribui\u00e7\u00e3o ao enfrentamento da discrimina\u00e7\u00e3o racial e na defesa dos direitos das mulheres no Estado\u201d, conforme a <a href=\"https:\/\/www.al.sp.gov.br\/repositorio\/legislacao\/resolucao.alesp\/2014\/resolucao.alesp-898-26.03.2014.html\" target=\"_blank\" rel=\"noopener noreferrer\">Resolu\u00e7\u00e3o<\/a> da Alesp.<\/p>\n<p>A deputada Leci Brand\u00e3o (PCdoB), que apresentou a proposta da homenagem, justificou a ideia: \u201cTheodosina sempre esteve comprometida com a valoriza\u00e7\u00e3o da cultura negra, a inclus\u00e3o social e a luta antidiscriminat\u00f3ria\u201d.<\/p>\n<p>Prestes a completar 90 anos, Theodosina morreu em 22 de abril de 2020. Foi homenageada por pol\u00edticos, militantes e institui\u00e7\u00f5es. A comiss\u00e3o de Igualdade Racial e Comiss\u00e3o da Verdade sobre a Escravid\u00e3o Negra, ambas da seccional de S\u00e3o Paulo da OAB, emitiram nota afirmando que ela \u201cretorna ao Orun [plano espiritual], deixando um legado inestim\u00e1vel na luta pelos direitos da popula\u00e7\u00e3o negra, ao qual todos n\u00f3s devemos celebrar e fazer jus\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fausto Salvadori | fausto@saopaulo.sp.leg.br Rodrigo Garcia | rodrigogarcia@saopaulo.sp.leg.br Com um nome raro, Theodosina Ros\u00e1rio Ribeiro nasceu em 1925, quando as mulheres ainda n\u00e3o tinham nem o direito a voto. Em quase 90 anos de vida, ela superou desafios e foi eleita a primeira vereadora negra da C\u00e2mara Municipal de S\u00e3o Paulo (CMSP). Como consequ\u00eancia de [&hellip;]<\/p>\n","protected":false},"author":579,"featured_media":47327,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1195,696,1202,1193,844,912,1205,1192,68,1206,69,1210,1209,1198,1200,1197,1208,492,424,1191,1204,865,1203,864,1196,1199,1194,26,1207,236,824,1189,1201,1190],"coauthors":[1211,1212],"class_list":["post-47325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-perfil","tag-adalberto-camargo","tag-ademar-de-barros","tag-alesp","tag-araraquara","tag-assembleia-legislativa","tag-assembleia-legislativa-de-sao-paulo","tag-assembleia-paulista","tag-barretos","tag-camara-municipal-de-sao-paulo","tag-claudete-alves","tag-cmsp","tag-comissao-da-verdade-sobre-a-escravidao-negra","tag-comissao-de-igualdade-racial","tag-comissao-de-igualdade-racial-da-ordem-dos-advogados-do-brasil","tag-cotas-raciais","tag-democrata","tag-discriminacao-racial","tag-forca-publica","tag-getulio-vargas","tag-jose-ignacio-do-rosario","tag-leci-brandao","tag-mdb","tag-medalha-theodosina-rosario-ribeiro","tag-movimento-democratico-brasileiro","tag-mulher-negra","tag-oab","tag-pirassununga","tag-politica","tag-povo-afro-brasileiro","tag-professores","tag-racismo","tag-theodosina-rosario-ribeiro","tag-titulo-de-cidada-paulistana","tag-vereadora-negra"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voz negra e pioneira nas tribunas - Apartes Digital<\/title>\n<meta name=\"description\" content=\"Theodosina Ros\u00e1rio Ribeiro nasceu em 1925, quando as mulheres ainda n\u00e3o tinham nem o direito a voto. Em quase 90 anos de vida, ela superou desafios e foi eleita a primeira vereadora negra da C\u00e2mara Municipal de S\u00e3o Paulo (CMSP).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voz negra e pioneira nas tribunas - Apartes Digital\" \/>\n<meta property=\"og:description\" content=\"Theodosina Ros\u00e1rio Ribeiro nasceu em 1925, quando as mulheres ainda n\u00e3o tinham nem o direito a voto. Em quase 90 anos de vida, ela superou desafios e foi eleita a primeira vereadora negra da C\u00e2mara Municipal de S\u00e3o Paulo (CMSP).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/\" \/>\n<meta property=\"og:site_name\" content=\"Apartes Digital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RevistaApartes\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-05T18:48:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T09:29:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-content\/uploads\/sites\/26\/2020\/07\/FOTO-3-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fausto Salvadori, Rodrigo Garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fausto Salvadori\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Fausto Salvadori, Rodrigo Garcia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/\"},\"author\":{\"name\":\"Fausto Salvadori\",\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/#\\\/schema\\\/person\\\/85ca999037a80801d3aab0b0e13c7d09\"},\"headline\":\"Voz negra e pioneira nas tribunas\",\"datePublished\":\"2020-08-05T18:48:43+00:00\",\"dateModified\":\"2025-11-26T09:29:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/\"},\"wordCount\":1230,\"publisher\":{\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2020\\\/07\\\/FOTO-3-scaled.jpg\",\"keywords\":[\"Adalberto Camargo\",\"Ademar de Barros\",\"Alesp\",\"Araraquara\",\"Assembleia Legislativa\",\"Assembleia Legislativa de S\u00e3o Paulo\",\"Assembleia Paulista\",\"Barretos\",\"C\u00e2mara Municipal de S\u00e3o Paulo\",\"Claudete Alves\",\"CMSP\",\"Comiss\u00e3o da Verdade sobre a Escravid\u00e3o Negra\",\"comiss\u00e3o de Igualdade Racial\",\"Comiss\u00e3o de Igualdade Racial da Ordem dos Advogados do Brasil\",\"cotas raciais\",\"democrata\",\"discrimina\u00e7\u00e3o racial\",\"For\u00e7a P\u00fablica\",\"Get\u00falio Vargas\",\"Jos\u00e9 Ign\u00e1cio do Ros\u00e1rio\",\"Leci Brand\u00e3o\",\"MDB\",\"medalha Theodosina Ros\u00e1rio Ribeiro\",\"Movimento Democr\u00e1tico Brasileiro\",\"mulher negra\",\"OAB\",\"Pirassununga\",\"pol\u00edtica\",\"povo afro-brasileiro\",\"professores\",\"racismo\",\"Theodosina Ros\u00e1rio Ribeiro\",\"T\u00edtulo de Cidad\u00e3 Paulistana\",\"vereadora negra\"],\"articleSection\":[\"Perfil\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/\",\"url\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/\",\"name\":\"Voz negra e pioneira nas tribunas - Apartes Digital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2020\\\/07\\\/FOTO-3-scaled.jpg\",\"datePublished\":\"2020-08-05T18:48:43+00:00\",\"dateModified\":\"2025-11-26T09:29:46+00:00\",\"description\":\"Theodosina Ros\u00e1rio Ribeiro nasceu em 1925, quando as mulheres ainda n\u00e3o tinham nem o direito a voto. Em quase 90 anos de vida, ela superou desafios e foi eleita a primeira vereadora negra da C\u00e2mara Municipal de S\u00e3o Paulo (CMSP).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2020\\\/07\\\/FOTO-3-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2020\\\/07\\\/FOTO-3-scaled.jpg\",\"width\":2560,\"height\":1718,\"caption\":\"Militante do empoderamento feminino, aconselhava as mulheres a participarem mais da pol\u00edtica | Gute Garbelotto\\\/CMSP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/voz-negra-e-pioneira-nas-tribunas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voz negra e pioneira nas tribunas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/#website\",\"url\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/\",\"name\":\"Apartes Digital\",\"description\":\"Vers\u00e3o digital da revista Apartes, publica\u00e7\u00e3o jornal\u00edstica da C\u00e2mara Municipal de S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/#organization\",\"name\":\"Revista Apartes - C\u00e2mara Municipal de S\u00e3o Paulo\",\"url\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2018\\\/03\\\/apartes_LOGOTIPO_VETOR_SEM_linha_explicativa_40px.png\",\"contentUrl\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2018\\\/03\\\/apartes_LOGOTIPO_VETOR_SEM_linha_explicativa_40px.png\",\"width\":149,\"height\":40,\"caption\":\"Revista Apartes - C\u00e2mara Municipal de S\u00e3o Paulo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RevistaApartes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCmyR103Wq_zss-097SvtC2g\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/#\\\/schema\\\/person\\\/85ca999037a80801d3aab0b0e13c7d09\",\"name\":\"Fausto Salvadori\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3186b3b11d52fbf82e7c0cf029567098384788cb16c0038fc4ba70dc6e90243?s=96&d=mm&r=g99958f35ce66eb6d9667b2f7c254f0c2\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3186b3b11d52fbf82e7c0cf029567098384788cb16c0038fc4ba70dc6e90243?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3186b3b11d52fbf82e7c0cf029567098384788cb16c0038fc4ba70dc6e90243?s=96&d=mm&r=g\",\"caption\":\"Fausto Salvadori\"},\"url\":\"https:\\\/\\\/www.saopaulo.sp.leg.br\\\/apartes\\\/author\\\/fausto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voz negra e pioneira nas tribunas - Apartes Digital","description":"Theodosina Ros\u00e1rio Ribeiro nasceu em 1925, quando as mulheres ainda n\u00e3o tinham nem o direito a voto. Em quase 90 anos de vida, ela superou desafios e foi eleita a primeira vereadora negra da C\u00e2mara Municipal de S\u00e3o Paulo (CMSP).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/","og_locale":"pt_BR","og_type":"article","og_title":"Voz negra e pioneira nas tribunas - Apartes Digital","og_description":"Theodosina Ros\u00e1rio Ribeiro nasceu em 1925, quando as mulheres ainda n\u00e3o tinham nem o direito a voto. Em quase 90 anos de vida, ela superou desafios e foi eleita a primeira vereadora negra da C\u00e2mara Municipal de S\u00e3o Paulo (CMSP).","og_url":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/","og_site_name":"Apartes Digital","article_publisher":"https:\/\/www.facebook.com\/RevistaApartes\/","article_published_time":"2020-08-05T18:48:43+00:00","article_modified_time":"2025-11-26T09:29:46+00:00","og_image":[{"width":2560,"height":1718,"url":"http:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-content\/uploads\/sites\/26\/2020\/07\/FOTO-3-scaled.jpg","type":"image\/jpeg"}],"author":"Fausto Salvadori, Rodrigo Garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fausto Salvadori","Est. tempo de leitura":"6 minutos","Written by":"Fausto Salvadori, Rodrigo Garcia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/#article","isPartOf":{"@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/"},"author":{"name":"Fausto Salvadori","@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/#\/schema\/person\/85ca999037a80801d3aab0b0e13c7d09"},"headline":"Voz negra e pioneira nas tribunas","datePublished":"2020-08-05T18:48:43+00:00","dateModified":"2025-11-26T09:29:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/"},"wordCount":1230,"publisher":{"@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/#organization"},"image":{"@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-content\/uploads\/sites\/26\/2020\/07\/FOTO-3-scaled.jpg","keywords":["Adalberto Camargo","Ademar de Barros","Alesp","Araraquara","Assembleia Legislativa","Assembleia Legislativa de S\u00e3o Paulo","Assembleia Paulista","Barretos","C\u00e2mara Municipal de S\u00e3o Paulo","Claudete Alves","CMSP","Comiss\u00e3o da Verdade sobre a Escravid\u00e3o Negra","comiss\u00e3o de Igualdade Racial","Comiss\u00e3o de Igualdade Racial da Ordem dos Advogados do Brasil","cotas raciais","democrata","discrimina\u00e7\u00e3o racial","For\u00e7a P\u00fablica","Get\u00falio Vargas","Jos\u00e9 Ign\u00e1cio do Ros\u00e1rio","Leci Brand\u00e3o","MDB","medalha Theodosina Ros\u00e1rio Ribeiro","Movimento Democr\u00e1tico Brasileiro","mulher negra","OAB","Pirassununga","pol\u00edtica","povo afro-brasileiro","professores","racismo","Theodosina Ros\u00e1rio Ribeiro","T\u00edtulo de Cidad\u00e3 Paulistana","vereadora negra"],"articleSection":["Perfil"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/","url":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/","name":"Voz negra e pioneira nas tribunas - Apartes Digital","isPartOf":{"@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/#primaryimage"},"image":{"@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-content\/uploads\/sites\/26\/2020\/07\/FOTO-3-scaled.jpg","datePublished":"2020-08-05T18:48:43+00:00","dateModified":"2025-11-26T09:29:46+00:00","description":"Theodosina Ros\u00e1rio Ribeiro nasceu em 1925, quando as mulheres ainda n\u00e3o tinham nem o direito a voto. Em quase 90 anos de vida, ela superou desafios e foi eleita a primeira vereadora negra da C\u00e2mara Municipal de S\u00e3o Paulo (CMSP).","breadcrumb":{"@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/#primaryimage","url":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-content\/uploads\/sites\/26\/2020\/07\/FOTO-3-scaled.jpg","contentUrl":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-content\/uploads\/sites\/26\/2020\/07\/FOTO-3-scaled.jpg","width":2560,"height":1718,"caption":"Militante do empoderamento feminino, aconselhava as mulheres a participarem mais da pol\u00edtica | Gute Garbelotto\/CMSP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/voz-negra-e-pioneira-nas-tribunas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/"},{"@type":"ListItem","position":2,"name":"Voz negra e pioneira nas tribunas"}]},{"@type":"WebSite","@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/#website","url":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/","name":"Apartes Digital","description":"Vers\u00e3o digital da revista Apartes, publica\u00e7\u00e3o jornal\u00edstica da C\u00e2mara Municipal de S\u00e3o Paulo","publisher":{"@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/#organization","name":"Revista Apartes - C\u00e2mara Municipal de S\u00e3o Paulo","url":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/#\/schema\/logo\/image\/","url":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-content\/uploads\/sites\/26\/2018\/03\/apartes_LOGOTIPO_VETOR_SEM_linha_explicativa_40px.png","contentUrl":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-content\/uploads\/sites\/26\/2018\/03\/apartes_LOGOTIPO_VETOR_SEM_linha_explicativa_40px.png","width":149,"height":40,"caption":"Revista Apartes - C\u00e2mara Municipal de S\u00e3o Paulo"},"image":{"@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RevistaApartes\/","https:\/\/www.youtube.com\/channel\/UCmyR103Wq_zss-097SvtC2g"]},{"@type":"Person","@id":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/#\/schema\/person\/85ca999037a80801d3aab0b0e13c7d09","name":"Fausto Salvadori","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a3186b3b11d52fbf82e7c0cf029567098384788cb16c0038fc4ba70dc6e90243?s=96&d=mm&r=g99958f35ce66eb6d9667b2f7c254f0c2","url":"https:\/\/secure.gravatar.com\/avatar\/a3186b3b11d52fbf82e7c0cf029567098384788cb16c0038fc4ba70dc6e90243?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3186b3b11d52fbf82e7c0cf029567098384788cb16c0038fc4ba70dc6e90243?s=96&d=mm&r=g","caption":"Fausto Salvadori"},"url":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/author\/fausto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/posts\/47325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/users\/579"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/comments?post=47325"}],"version-history":[{"count":0,"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/posts\/47325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/media\/47327"}],"wp:attachment":[{"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/media?parent=47325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/categories?post=47325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/tags?post=47325"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.saopaulo.sp.leg.br\/apartes\/wp-json\/wp\/v2\/coauthors?post=47325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}